{"id":45990,"date":"2024-09-04T21:40:36","date_gmt":"2024-09-04T19:40:36","guid":{"rendered":"https:\/\/www.amt.genova.it\/amt\/?p=45990"},"modified":"2024-09-09T22:21:38","modified_gmt":"2024-09-09T20:21:38","slug":"sagra-del-fuoco-a-recco-corse-speciali-e-variazioni-ai-percorsi","status":"publish","type":"post","link":"https:\/\/www.amt.genova.it\/amt\/sagra-del-fuoco-a-recco-corse-speciali-e-variazioni-ai-percorsi\/","title":{"rendered":"Sagra del Fuoco a Recco. Corse speciali e variazioni ai percorsi"},"content":{"rendered":"<p>** A causa del perdurare delle condizioni meteo le corse speciali per lo spettacolo pirotecnico in programma domenica 8 settembre sono annullate**.<br \/>\nIn occasione della Sagra del Fuoco, nelle serate di <strong>sabato 7 e domenica 8 settembre<\/strong> AMT effettuer\u00e0 <strong>corse straordinarie<\/strong> per Recco. I dettagli sono indicati di seguito:<\/p>\n<ul>\n<li>20.30 da Calcinara<\/li>\n<li>20.30 da Gattorna<\/li>\n<li>20.30 da Rapallo con transito da Santa Margherita Ligure (San Lorenzo e Ruta)<\/li>\n<li>20.30 da Genova viale Caviglia<\/li>\n<li>20.40 da Genova viale Caviglia<\/li>\n<\/ul>\n<p>Le corse per il rientro da Recco per Gattorna, Colle Caprile, Rapallo, Santa Margherita Ligure, Camogli e Genova partiranno dal capolinea di Recco 30 minuti dopo la fine dell\u2019ultimo spettacolo pirotecnico.<\/p>\n<p>Informiamo inoltre che in tali giorni verranno modificati alcuni percorsi delle linee in arrivo e partenza presso il <strong>capolinea di Recco<\/strong>:<\/p>\n<ul>\n<li><strong>Linee provenienti da Calcinara, Serro e Testana<\/strong>: i bus giunti al bivio A12, transiteranno in via Pisa, piazza Gastaldi, via Marconi sino alla rotonda svoltando a sinistra per raggiungere il capolinea;<\/li>\n<li><strong>Linee per <\/strong>Calcinara, Serro e Testana: i bus percorreranno via XXV Aprile, via Pisa, via Roma dove riprenderanno regolare percorso.<\/li>\n<li><strong>Servizio Chiamabus<\/strong>:\n<ul>\n<li>i bus provenienti <strong>da Verzemma e Liceto<\/strong> giunti al bivio A12 transiteranno in via Pisa, piazza Gastaldi, via Marconi sino alla rotonda svoltando a sinistra per raggiungere il capolinea. In direzione opposta i bus percorreranno via XXV Aprile, via Pisa, via Roma dove riprenderanno regolare percorso;<\/li>\n<li>i bus provenienti <strong>da Cotulo<\/strong> arrivati in via XX Settembre proseguiranno fino in piazza San Giovanni Bono e poi svolteranno in via Roma. Da Recco per Cotulo i bus transiteranno davanti alla parrocchia di San Giovanni Bono, via San Giovanni Battista, via Liceti, via XX Settembre per riprendere regolare percorso.<\/li>\n<li>Servizio regolare per le localit\u00e0 di <strong>Ageno e Carbonara.<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n ","protected":false},"excerpt":{"rendered":"** A causa del perdurare delle condizioni meteo le corse speciali per lo spettacolo pirotecnico in programma domenica 8 settembre sono annullate**. In occasione della Sagra del Fuoco, nelle serate di sabato 7 e domenica 8 settembre AMT effettuer\u00e0 corse straordinarie per Recco. I dettagli sono indicati di seguito: 20.30 da Calcinara 20.30 da Gattorna 20.30 da Rapallo con transito&nbsp;<a href=\"https:\/\/www.amt.genova.it\/amt\/sagra-del-fuoco-a-recco-corse-speciali-e-variazioni-ai-percorsi\/\" class=\"read-more\">Continue Reading<\/a>","protected":false},"author":2,"featured_media":40401,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,65],"tags":[],"class_list":["post-45990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","category-provinciale","cat-4-id","cat-65-id"],"_links":{"self":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/45990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/comments?post=45990"}],"version-history":[{"count":4,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/45990\/revisions"}],"predecessor-version":[{"id":46039,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/45990\/revisions\/46039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/media\/40401"}],"wp:attachment":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/media?parent=45990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/categories?post=45990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/tags?post=45990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}