{"id":38859,"date":"2023-05-19T14:56:45","date_gmt":"2023-05-19T12:56:45","guid":{"rendered":"https:\/\/www.amt.genova.it\/amt\/?p=38859"},"modified":"2023-10-26T15:51:06","modified_gmt":"2023-10-26T13:51:06","slug":"linee-17-42-617-e-641-variazioni-temporanee-di-percorso-prorogate-a-sabato-10-giugno","status":"publish","type":"post","link":"https:\/\/www.amt.genova.it\/amt\/linee-17-42-617-e-641-variazioni-temporanee-di-percorso-prorogate-a-sabato-10-giugno\/","title":{"rendered":"Linee 17\/, 42, 617 e 641 variazioni di percorso prorogate a sabato 10 giugno"},"content":{"rendered":"<p>Si informa che le modifiche al servizio serale delle <strong>linee 17\/, 42, 617 e 641, <\/strong>dovute all'interdizione al traffico veicolare in galleria Colombo per interventi sul sistema di illuminazione (leggi la precedente notizia <a href=\"https:\/\/www.amt.genova.it\/amt\/linee-17-42-617-e-641-variazioni-temporanee-di-percorso-da-lunedi-17-aprile-a-sabato-20-maggio\/\">qui<\/a>),<strong> sono state prorogate a sabato 10 giugno.<\/strong><\/p>\n<p><strong>Pertanto, fino a sabato 10 giugno<\/strong> (sabato, domenica e giornate festive escluse), le linee 17\/, 42, 617 e 641 modificheranno il\u00a0servizio di notte,\u00a0<strong>dalle ore 21.30 fino alle ore 6.00<\/strong>\u00a0del giorno successivo, come di seguito indicato.<\/p>\n<ul>\n<li><strong>Linea 17\/<\/strong><\/li>\n<\/ul>\n<p><strong>Direzione levante:\u00a0<\/strong>i bus, in partenza dal capolinea di via Ceccardi, proseguono per piazza Dante, via Fieschi, via XX Settembre, via Fiume dove riprendono regolare percorso.<br \/>\n<strong>Direzione ponente:<\/strong>\u00a0percorso regolare.<\/p>\n<ul>\n<li><strong>Linea 42<\/strong><\/li>\n<\/ul>\n<p><strong>Direzione levante:<\/strong>\u00a0i bus, in partenza dal capolinea di via Dante, proseguono per piazza Dante, via Fieschi, via XX Settembre, via Cadorna, viale Brigata Bisagno, via Diaz, corso Buenos Aires dove riprendono regolare percorso.<br \/>\n<strong>Direzione ponente:\u00a0<\/strong>percorso regolare.<\/p>\n<ul>\n<li><strong>Linea 617<\/strong><\/li>\n<\/ul>\n<p><strong>Direzione levante:<\/strong>\u00a0i bus, giunti in via Dante, proseguono per piazza Dante, via Fieschi, via XX Settembre, via Fiume dove riprendono regolare percorso.<br \/>\n<strong>Direzione ponente:\u00a0<\/strong>percorso regolare.<\/p>\n<ul>\n<li><strong>Linea 641<\/strong><\/li>\n<\/ul>\n<p><strong>Direzione levante:<\/strong>\u00a0i bus, giunti in via Dante, proseguono per piazza Dante, via Fieschi, via XX Settembre, via Cadorna, viale Brigata Bisagno, viale Brigata Bisagno, corso Buenos Aires dove riprenderanno regolare percorso.<br \/>\n<strong>Direzione ponente:\u00a0<\/strong>percorso regolare.<\/p>\n ","protected":false},"excerpt":{"rendered":"Si informa che le modifiche al servizio serale delle linee 17\/, 42, 617 e 641, dovute all'interdizione al traffico veicolare in galleria Colombo per interventi sul sistema di illuminazione (leggi la precedente notizia qui), sono state prorogate a sabato 10 giugno. Pertanto, fino a sabato 10 giugno (sabato, domenica e giornate festive escluse), le linee 17\/, 42, 617 e 641&nbsp;<a href=\"https:\/\/www.amt.genova.it\/amt\/linee-17-42-617-e-641-variazioni-temporanee-di-percorso-prorogate-a-sabato-10-giugno\/\" class=\"read-more\">Continue Reading<\/a>","protected":false},"author":2,"featured_media":35270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,64],"tags":[],"class_list":["post-38859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","category-urbano","cat-4-id","cat-64-id"],"_links":{"self":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/38859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/comments?post=38859"}],"version-history":[{"count":2,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/38859\/revisions"}],"predecessor-version":[{"id":38861,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/38859\/revisions\/38861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/media\/35270"}],"wp:attachment":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/media?parent=38859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/categories?post=38859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/tags?post=38859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}