{"id":30895,"date":"2022-01-05T13:08:51","date_gmt":"2022-01-05T12:08:51","guid":{"rendered":"https:\/\/www.amt.genova.it\/amt\/?p=30895"},"modified":"2022-01-05T13:08:51","modified_gmt":"2022-01-05T12:08:51","slug":"chiusura-di-via-cornigliano-variazioni-delle-linee-bus-dal-7-al-10-gennaio","status":"publish","type":"post","link":"https:\/\/www.amt.genova.it\/amt\/chiusura-di-via-cornigliano-variazioni-delle-linee-bus-dal-7-al-10-gennaio\/","title":{"rendered":"Chiusura di via Cornigliano variazioni delle linee bus dal 7 al 10 gennaio"},"content":{"rendered":"<p>Si informa \u00a0che, a seguito della chiusura al transito veicolare di via Cornigliano, prevista <strong>dalle ore 22.00 di venerd\u00ec 7 gennaio fino alle ore 4.00 di luned\u00ec 10 gennaio<\/strong>, e comunque fino a cessate esigenze, le <strong>linee 1, 160 e N2 <\/strong>modificheranno il percorso come di seguito indicato.<\/p>\n<p><strong>Linee 1 e N2<\/strong><\/p>\n<ul>\n<li><strong>Direzione Voltri<\/strong>: i bus, giunti al termine di via Avio, proseguiranno per via Pacinotti, lungomare Canepa, via Guido Rossa e piazza Savio dove riprenderanno regolare percorso.<\/li>\n<li><strong>Direzione Caricamento<\/strong>: i bus, giunti al termine di via Siffredi proseguiranno per via Guido Rossa, lungomare Canepa, via Balleydier, via P.Chiesa, lungomare Canepa, via Molteni e via Avio, piazza Vittorio Veneto, via Cantore dove riprenderanno regolare percorso.<\/li>\n<\/ul>\n<p><strong>Si precisa che in entrambe le direzioni non verranno effettuate fermate in via Guido Rossa e lungomare Canepa. <\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Linea 160<\/strong>: nelle giornate <strong>di sabato 8 e domenica 9 gennaio<\/strong>, da inizio a fine servizio, la linea 160 modificher\u00e0 il percorso come segue: i bus giunti al termine di via Alessandro Malaspina, proseguiranno per via Tonale, via dei Domenicani, via Marino Tomaso, via Giacomo Oneto, via Mario Piana, via Cornigliano, via Lorenzo Dufour dove effettueranno regolare capolinea.<\/p>\n<p><strong>Bus navetta Principe - Massena<\/strong><\/p>\n<p>Contestualmente alle variazioni di percorso verr\u00e0 istituito <strong>un bus navetta<\/strong> sul seguente percorso circolare: piazza Acquaverde, via Andrea Doria, via San Benedetto, via Buozzi, piazza Dinegro, via Cantore, piazza Montano FS, piazza Veneto, via Avio, via Pieragostini, piazza Massena, corso Perrone, rotatoria via Bianchi, corso Perrone, piazza Massena, via Pieragostini, via Pacinotti, via Sampierdarena, via di Francia, via Buozzi, via San Benedetto, piazza Acquaverde. <strong>Il bus navetta sar\u00e0 in servizio sabato e domenica dalle ore 6.00 alle ore 21.00 con frequenza di 11 minuti.<\/strong><\/p>\n<p><strong>Bus navetta Cornigliano<\/strong><\/p>\n<p>Contestualmente alle variazioni di percorso verr\u00e0 istituito <strong>un bus navetta<\/strong> sul percorso circolare piazza Massena, via San Giovanni D\u2019Acri, via Guido Rossa, piazza Savio, via Siffredi, rotatoria via Siffredi\/via dell\u2019Acciaio, via Siffredi, via Guido Rossa, via San Giovanni D\u2019Acri, piazza Massena. <strong>Il bus navetta sar\u00e0 in servizio sabato e domenica dalle ore 7.00 alle ore 20.00 con frequenza di 20 minuti. <\/strong><strong>Si precisa che non verranno effettuate fermate in via Guido Rossa. <\/strong><\/p>\n<p>&nbsp;<\/p>\n ","protected":false},"excerpt":{"rendered":"Si informa \u00a0che, a seguito della chiusura al transito veicolare di via Cornigliano, prevista dalle ore 22.00 di venerd\u00ec 7 gennaio fino alle ore 4.00 di luned\u00ec 10 gennaio, e comunque fino a cessate esigenze, le linee 1, 160 e N2 modificheranno il percorso come di seguito indicato. Linee 1 e N2 Direzione Voltri: i bus, giunti al termine di&nbsp;<a href=\"https:\/\/www.amt.genova.it\/amt\/chiusura-di-via-cornigliano-variazioni-delle-linee-bus-dal-7-al-10-gennaio\/\" class=\"read-more\">Continue Reading<\/a>","protected":false},"author":2,"featured_media":18799,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,4,64],"tags":[],"class_list":["post-30895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage","category-notizie","category-urbano","cat-56-id","cat-4-id","cat-64-id"],"_links":{"self":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/30895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/comments?post=30895"}],"version-history":[{"count":1,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/30895\/revisions"}],"predecessor-version":[{"id":30896,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/30895\/revisions\/30896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/media\/18799"}],"wp:attachment":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/media?parent=30895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/categories?post=30895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/tags?post=30895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}