{"id":30857,"date":"2022-01-01T18:30:25","date_gmt":"2022-01-01T17:30:25","guid":{"rendered":"https:\/\/www.amt.genova.it\/amt\/?p=30857"},"modified":"2022-01-07T12:18:28","modified_gmt":"2022-01-07T11:18:28","slug":"ferrovia-genova-casella-le-modalita-di-svolgimento-del-servizio-dal-1-al-7-gennaio","status":"publish","type":"post","link":"https:\/\/www.amt.genova.it\/amt\/ferrovia-genova-casella-le-modalita-di-svolgimento-del-servizio-dal-1-al-7-gennaio\/","title":{"rendered":"Ferrovia Genova &#8211; Casella, le modalit\u00e0 di svolgimento del servizio dal 1\u00b0 al 7 gennaio"},"content":{"rendered":"<p>Si informa che <strong>da sabato 1\u00b0 a venerd\u00ec 7 gennaio<\/strong> il servizio della ferrovia Genova Casella sar\u00e0 svolto con le modalit\u00e0 di seguito indicate.<\/p>\n<h3><strong>Sabato 1\u00b0 gennaio e gioved\u00ec 6 gennaio<\/strong><\/h3>\n<p>Sar\u00e0 in vigore <strong>il servizio speciale<\/strong> sotto riportato. Tutte le corse verranno svolte con il treno.<\/p>\n<ul>\n<li><strong><em>Partenze da Genova<\/em><\/strong>: 9.00 - 11.50 - 16.15 - 18.55<\/li>\n<li><strong><em>Partenze da Casella<\/em><\/strong>: 7.35 - 10.28 - 14.50 - 17.32<\/li>\n<\/ul>\n<p>Sabato 1\u00b0gennaio il Museo della ferrovia, allestito alla stazione di Crocetta d\u2019Orero, rester\u00e0 chiuso.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Domenica 2 gennaio<\/strong><\/h3>\n<p>Il servizio della ferrovia Genova - Casella sar\u00e0 svolto in <strong>modalit\u00e0 mista treno e bus sostitutivo<\/strong> come di seguito indicato.<\/p>\n<ul>\n<li>Corse effettuate <strong>con il treno<\/strong>: partenze <strong>da Casella<\/strong> delle ore 7.35 \u2013 10.28 \u2013 14.50 \u2013 17.32. Partenze <strong>da Genova<\/strong> delle ore 9.00 \u2013 11.50 \u2013 16.15 \u2013 18.55.<\/li>\n<li>Corse effettuate\u00a0<strong>con il bus sostitutivo<\/strong>:partenze da Casella delle ore 13,16 \u2013 16,05 \u2013 18,45 e da Genova delle ore 10,20 \u2013 13,10 \u2013 14,45 \u2013 17,27.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>Da luned\u00ec 3 a mercoled\u00ec 5 gennaio e venerd\u00ec 7 gennaio<\/strong><\/h3>\n<p>Il servizio della ferrovia Genova - Casella sar\u00e0 svolto in <strong>modalit\u00e0 mista treno e bus sostitutivo<\/strong> come di seguito indicato.<\/p>\n<ul>\n<li>Corse effettuate<strong> con il treno:<\/strong> partenze <strong>da Casella<\/strong> delle ore 6.20 \u2013 7.27 \u2013 8.52 \u2013 10.38<br \/>\ne <strong>da Genova<\/strong> delle ore 7.35 \u2013 9.00 \u2013 12.08 \u2013 13.23.<\/li>\n<li>Corse effettuate<strong> con il bus sostitutivo<\/strong>: partenze <strong>da Casella<\/strong> delle ore 13.15 \u2013 14.58 \u2013 16.38 \u2013 18.08 - 19.27 e <strong>da Genova<\/strong> delle ore 10.30 \u2013 14.30 \u2013 16.46 \u2013 18.00 \u2013 19.35.<\/li>\n<\/ul>\n<p>La modalit\u00e0 mista treno\/bus si rende necessaria a seguito delle segnalazioni preventive di assenza per mancanza di Green Pass ricevute dal personale della ferrovia.<\/p>\n<p>L\u2019azienda fornir\u00e0 ulteriori informazioni su eventuali variazioni del servizio.<\/p>\n ","protected":false},"excerpt":{"rendered":"Si informa che da sabato 1\u00b0 a venerd\u00ec 7 gennaio il servizio della ferrovia Genova Casella sar\u00e0 svolto con le modalit\u00e0 di seguito indicate. Sabato 1\u00b0 gennaio e gioved\u00ec 6 gennaio Sar\u00e0 in vigore il servizio speciale sotto riportato. Tutte le corse verranno svolte con il treno. Partenze da Genova: 9.00 - 11.50 - 16.15 - 18.55 Partenze da Casella:&nbsp;<a href=\"https:\/\/www.amt.genova.it\/amt\/ferrovia-genova-casella-le-modalita-di-svolgimento-del-servizio-dal-1-al-7-gennaio\/\" class=\"read-more\">Continue Reading<\/a>","protected":false},"author":2,"featured_media":14743,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-30857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","cat-4-id"],"_links":{"self":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/30857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/comments?post=30857"}],"version-history":[{"count":6,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/30857\/revisions"}],"predecessor-version":[{"id":30877,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/30857\/revisions\/30877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/media\/14743"}],"wp:attachment":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/media?parent=30857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/categories?post=30857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/tags?post=30857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}