{"id":30505,"date":"2021-12-17T15:22:23","date_gmt":"2021-12-17T14:22:23","guid":{"rendered":"https:\/\/www.amt.genova.it\/amt\/?p=30505"},"modified":"2021-12-17T15:24:13","modified_gmt":"2021-12-17T14:24:13","slug":"linee-amt-per-lincontro-di-calcio-sampdoria-venezia-domenica-19-dicembre","status":"publish","type":"post","link":"https:\/\/www.amt.genova.it\/amt\/linee-amt-per-lincontro-di-calcio-sampdoria-venezia-domenica-19-dicembre\/","title":{"rendered":"Linee AMT per l\u2019incontro di calcio Sampdoria &#8211; Venezia domenica 19 dicembre"},"content":{"rendered":"<p>In occasione dell\u2019incontro di calcio <strong>Sampdoria - Venezia, in programma domenica 19 dicembre alle ore 18.00<\/strong> allo stadio Luigi Ferraris, sar\u00e0 attivo il servizio delle linee BM (Molassana - Stadio) con arrivo a piazzale Marassi, CM (Caricamento - Stadio) e KM (piazzale Kennedy - Stadio) con arrivo a via Bonifacio, SM (piazza Acquaverde - Stadio) con arrivo in via Monticelli.<br \/>\nEcco in dettaglio gli orari delle linee:<\/p>\n<p><strong>BM corse da Molassana:<\/strong><br \/>\n16.00 16.15 16.35 16.55 17.10 17.30 17.45<\/p>\n<p><strong>CM corse da Caricamento:<\/strong><br \/>\n15.55 16.10 16.30 16.50 17.05 17.25 17.40<\/p>\n<p><strong>KM corse da piazzale Kennedy:<\/strong><br \/>\n16.00 16.10 16.20 16.30 16.40 16.50 17.00 17.10 17.20 17.30 17.40 17.50<\/p>\n<p><strong>SM corse da piazza Acquaverde:<\/strong><br \/>\n16.00 16.10 16.20 16.30 16.40 16.50 17.00 17.10 17.20 17.30 17.40 17.50<\/p>\n<p>Al termine dell\u2019incontro saranno in funzione le stesse linee speciali in partenza da via Monticelli, via Bonifacio e piazzale Marassi. Ricordiamo le altre principali linee transitanti in zona Stadio: 13 (Prato - Caricamento), 37 (via dei Platani - via Dante\/De Ferrari), 48 (Molassana - PS San Martino), 82 (Brignole \u2013 Quezzi), 480 (stazione Brignole - Sant\u2019Eusebio) e 482 (stazione Brignole - Sant\u2019Eusebio).<\/p>\n ","protected":false},"excerpt":{"rendered":"In occasione dell\u2019incontro di calcio Sampdoria - Venezia, in programma domenica 19 dicembre alle ore 18.00 allo stadio Luigi Ferraris, sar\u00e0 attivo il servizio delle linee BM (Molassana - Stadio) con arrivo a piazzale Marassi, CM (Caricamento - Stadio) e KM (piazzale Kennedy - Stadio) con arrivo a via Bonifacio, SM (piazza Acquaverde - Stadio) con arrivo in via Monticelli.&nbsp;<a href=\"https:\/\/www.amt.genova.it\/amt\/linee-amt-per-lincontro-di-calcio-sampdoria-venezia-domenica-19-dicembre\/\" class=\"read-more\">Continue Reading<\/a>","protected":false},"author":2,"featured_media":18702,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,64],"tags":[],"class_list":["post-30505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","category-urbano","cat-4-id","cat-64-id"],"_links":{"self":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/30505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/comments?post=30505"}],"version-history":[{"count":1,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/30505\/revisions"}],"predecessor-version":[{"id":30506,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/posts\/30505\/revisions\/30506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/media\/18702"}],"wp:attachment":[{"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/media?parent=30505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/categories?post=30505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amt.genova.it\/amt\/wp-json\/wp\/v2\/tags?post=30505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}